{"id":5265,"date":"2024-03-21T13:50:34","date_gmt":"2024-03-21T12:50:34","guid":{"rendered":"https:\/\/www.turismehostalric.cat\/el-que-pots-visitar\/visita-guiada-al-castillo-de-hostalric\/"},"modified":"2026-01-15T12:41:26","modified_gmt":"2026-01-15T11:41:26","slug":"visita-guiada-al-castillo-de-hostalric","status":"publish","type":"el-que-pots-visitar","link":"https:\/\/www.turismehostalric.cat\/es\/el-que-pots-visitar\/visita-guiada-al-castillo-de-hostalric\/","title":{"rendered":"Visita guiada al Castillo de Hostalric"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5265\" class=\"elementor elementor-5265 elementor-663\" data-elementor-post-type=\"el-que-pots-visitar\">\n\t\t\t\t<div class=\"elementor-element elementor-element-669b1b69 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"669b1b69\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-53ba84f2 elementor-widget elementor-widget-text-editor\" data-id=\"53ba84f2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Descubra la historia del Castillo de Hostalric con esta visita guiada conducida por gu\u00edas locales acreditadas y ad\u00e9ntrate en una de las fortalezas m\u00e1s importantes de Catalu\u00f1a.<\/p><p class=\"p1\">A trav\u00e9s de un recorrido de aproximadamente 1 hora y 30 minutos, conocer\u00e1 c\u00f3mo el castillo medieval de los Vizcondes de Cabrera evolucion\u00f3 para convertirse en una fortificaci\u00f3n moderna adaptada a las nuevas t\u00e9cnicas militares. Las gu\u00edas le explicar\u00e1n c\u00f3mo y por qu\u00e9 se transform\u00f3, qu\u00e9 sistemas defensivos se utilizaron y qu\u00e9 acontecimientos hist\u00f3ricos han marcado su evoluci\u00f3n. <\/p><p class=\"p1\">Durante la visita, podr\u00e1 descubrir espacios emblem\u00e1ticos de la fortaleza de Hostalric como el cuerpo de guardia, los baluartes, el polvor\u00edn o la galer\u00eda a prueba de bomba, aut\u00e9nticos testigos de su funci\u00f3n militar y del papel clave que jug\u00f3 en la historia de Catalu\u00f1a. Desde algunos puntos del recorrido, tambi\u00e9n podr\u00e1 disfrutar de magn\u00edficas vistas sobre el macizo del Montseny, el Castillo de Montsoriu y el entorno natural de la llanura selvatana. <\/p><p class=\"p1\">Nota: debido a unas obras de mejora y restauraci\u00f3n al caballero y al patio de armas, estos espacios permanecer\u00e1n temporalmente cerrados al p\u00fablico. El recorrido de la visita guiada al Castillo de Hostalric se ha adaptado para ofrecer una experiencia igualmente completa, que permite descubrir la esencia hist\u00f3rica, arquitect\u00f3nica y paisaj\u00edstica de este conjunto patrimonial Bien Cultural de Inter\u00e9s Nacional. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a70183 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"2a70183\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MjQzNSwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Consulta las fechas disponibles y RESERVA TU VISITA.<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5aae953 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"5aae953\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-539f3fc e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"539f3fc\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e9d389c elementor-widget-divider--view-line_text elementor-widget-divider--element-align-left elementor-widget elementor-widget-divider\" data-id=\"e9d389c\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<span class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\tHorarios visitas guiadas\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c9463a elementor-widget elementor-widget-text-editor\" data-id=\"6c9463a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Del 1\/09 al 30\/06: s\u00e1bados, domingos<br> y festivos a las 12h*<\/p><p><strong>Del 01\/07 al 31\/08: s\u00e1bado, domingos<br> y festivos a las 11h<\/strong> *<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c1c57e8 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"c1c57e8\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-62bd559 elementor-widget-divider--view-line_text elementor-widget-divider--element-align-left elementor-widget elementor-widget-divider\" data-id=\"62bd559\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<span class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\tTarifas\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d54d74e elementor-widget elementor-widget-text-editor\" data-id=\"d54d74e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Tarifa general<\/strong> : 7\u20ac<br><strong style=\"color: var( --e-global-color-b96a02b ); font-family: var( --e-global-typography-5e9ee57-font-family ), Sans-serif; font-size: var( --e-global-typography-5e9ee57-font-size ); letter-spacing: var( --e-global-typography-5e9ee57-letter-spacing ); word-spacing: var( --e-global-typography-5e9ee57-word-spacing ); background-color: var(--base-2);\">Tarifa reducida:<\/strong> <span style=\"color: var( --e-global-color-b96a02b ); font-family: var( --e-global-typography-5e9ee57-font-family ), Sans-serif; font-size: var( --e-global-typography-5e9ee57-font-size ); letter-spacing: var( --e-global-typography-5e9ee57-letter-spacing ); word-spacing: var( --e-global-typography-5e9ee57-word-spacing ); background-color: var(--base-2);\"><span style=\"font-weight: var( --e-global-typography-5e9ee57-font-weight );\">5\u20ac (ni\u00f1os de 7 a 18 a\u00f1os, \u00abCarnet Jove\u00bb, diversidad funcional y mayores de 65 a\u00f1os)<\/span><br><\/span> <span style=\"color: var( --e-global-color-b96a02b ); font-family: var( --e-global-typography-5e9ee57-font-family ), Sans-serif; font-size: var( --e-global-typography-5e9ee57-font-size ); letter-spacing: var( --e-global-typography-5e9ee57-letter-spacing ); word-spacing: var( --e-global-typography-5e9ee57-word-spacing ); background-color: var(--base-2);\"><b>Entrada gratuita:<\/b> menores de 6 a\u00f1os y Carnet S\u00faper 3.<b><br><\/b><\/span> <span style=\"background-color: var(--base-2); color: var( --e-global-color-b96a02b ); font-family: var( --e-global-typography-5e9ee57-font-family ), Sans-serif; font-size: var( --e-global-typography-5e9ee57-font-size ); letter-spacing: var( --e-global-typography-5e9ee57-letter-spacing ); word-spacing: var( --e-global-typography-5e9ee57-word-spacing ); font-weight: var( --e-global-typography-5e9ee57-font-weight );\">(excepto grupos escolares).<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e92a88f e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"e92a88f\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d314a6f elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"d314a6f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>S\u00f3lo se admiten pagos en tarjeta seg\u00fan Acuerdo de Junta de Gobierno local celebrada el 14 de abril de 2025.<\/strong><br><strong>Plazas limitadas. Recomendamos reserva previa y consultar el calendario de disponibilidad. <\/strong><\/p><p>* Las visitas guiadas se hacen en catal\u00e1n.<br>Para otros idiomas, contacte con nosotros a turisme@hostalric.cat o al 972874165 y le informaremos de las posibilidades.<\/p><p>Punto de inicio de la visita: Punto de Informaci\u00f3n del Castell.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0cf4370 elementor-widget elementor-widget-text-editor\" data-id=\"0cf4370\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La organizaci\u00f3n se reserva el derecho a modificar las disponibilidades descritas anteriormente.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Descubra la historia del Castillo de Hostalric con esta visita guiada conducida por gu\u00edas locales acreditadas y ad\u00e9ntrate en una de las fortalezas m\u00e1s importantes de Catalu\u00f1a. A trav\u00e9s de un recorrido de aproximadamente 1 hora y 30 minutos, conocer\u00e1 c\u00f3mo el castillo medieval de los Vizcondes de Cabrera evolucion\u00f3 para convertirse en una fortificaci\u00f3n moderna adaptada a las nuevas t\u00e9cnicas militares. Las gu\u00edas le explicar\u00e1n c\u00f3mo y por qu\u00e9 se transform\u00f3, qu\u00e9 sistemas defensivos se utilizaron y qu\u00e9 acontecimientos hist\u00f3ricos han marcado su evoluci\u00f3n. Durante la visita, podr\u00e1 descubrir espacios emblem\u00e1ticos de la fortaleza de Hostalric como el cuerpo de guardia, los baluartes, el polvor\u00edn o la galer\u00eda a prueba de bomba, aut\u00e9nticos testigos de su funci\u00f3n militar y del papel clave que jug\u00f3 en la historia de Catalu\u00f1a. Desde algunos puntos del recorrido, tambi\u00e9n podr\u00e1 disfrutar de magn\u00edficas vistas sobre el macizo del Montseny, el Castillo de Montsoriu y el entorno natural de la llanura selvatana. Nota: debido a unas obras de mejora y restauraci\u00f3n al caballero y al patio de armas, estos espacios permanecer\u00e1n temporalmente cerrados al p\u00fablico. El recorrido de la visita guiada al Castillo de Hostalric se ha adaptado para ofrecer una experiencia igualmente completa, que permite descubrir la esencia hist\u00f3rica, arquitect\u00f3nica y paisaj\u00edstica de este conjunto patrimonial Bien Cultural de Inter\u00e9s Nacional. Consulta las fechas disponibles y RESERVA TU VISITA. Horarios visitas guiadas Del 1\/09 al 30\/06: s\u00e1bados, domingos y festivos a las 12h* Del 01\/07 al 31\/08: s\u00e1bado, domingos y festivos a las 11h * Tarifas Tarifa general : 7\u20acTarifa reducida: 5\u20ac (ni\u00f1os de 7 a 18 a\u00f1os, \u00abCarnet Jove\u00bb, diversidad funcional y mayores de 65 a\u00f1os) Entrada gratuita: menores de 6 a\u00f1os y Carnet S\u00faper 3. (excepto grupos escolares). S\u00f3lo se admiten pagos en tarjeta seg\u00fan Acuerdo de Junta de Gobierno local celebrada el 14 de abril de 2025.Plazas limitadas. Recomendamos reserva previa y consultar el calendario de disponibilidad. * Las visitas guiadas se hacen en catal\u00e1n.Para otros idiomas, contacte con nosotros a turisme@hostalric.cat o al 972874165 y le informaremos de las posibilidades. Punto de inicio de la visita: Punto de Informaci\u00f3n del Castell. La organizaci\u00f3n se reserva el derecho a modificar las disponibilidades descritas anteriormente.<\/p>\n","protected":false},"featured_media":2579,"template":"","meta":{"_acf_changed":false},"class_list":["post-5265","el-que-pots-visitar","type-el-que-pots-visitar","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.turismehostalric.cat\/es\/wp-json\/wp\/v2\/el-que-pots-visitar\/5265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.turismehostalric.cat\/es\/wp-json\/wp\/v2\/el-que-pots-visitar"}],"about":[{"href":"https:\/\/www.turismehostalric.cat\/es\/wp-json\/wp\/v2\/types\/el-que-pots-visitar"}],"version-history":[{"count":16,"href":"https:\/\/www.turismehostalric.cat\/es\/wp-json\/wp\/v2\/el-que-pots-visitar\/5265\/revisions"}],"predecessor-version":[{"id":7109,"href":"https:\/\/www.turismehostalric.cat\/es\/wp-json\/wp\/v2\/el-que-pots-visitar\/5265\/revisions\/7109"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.turismehostalric.cat\/es\/wp-json\/wp\/v2\/media\/2579"}],"wp:attachment":[{"href":"https:\/\/www.turismehostalric.cat\/es\/wp-json\/wp\/v2\/media?parent=5265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}